{"id":443,"date":"2022-12-21T11:09:21","date_gmt":"2022-12-21T11:09:21","guid":{"rendered":"https:\/\/jessgrove.co.uk\/?p=443"},"modified":"2022-12-21T12:08:21","modified_gmt":"2022-12-21T12:08:21","slug":"viscosa","status":"publish","type":"post","link":"https:\/\/jessgrove.co.uk\/it\/viscose\/","title":{"rendered":"Viscosa"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row inverted-device-order has-bg need-focus style-color-lxmt-bg row-container has-dividers\" id=\"row-unique-0\"><div class=\"uncode-divider-wrap uncode-divider-wrap-bottom z_index_0 uncode-divider-mobile-hide\" style=\"height: 50px;\" data-height=\"50\" data-unit=\"px\"><svg version=\"1.1\" class=\"uncode-row-divider uncode-row-divider-mountains\" x=\"0px\" y=\"0px\" width=\"240px\" height=\"24px\" viewbox=\"0 0 240 24\" enable-background=\"new 0 0 240 24\" xml:space=\"preserve\" preserveaspectratio=\"none\">\n\t\t<path fill=\"#ffffff\" d=\"M240,24v-3.896c-1.68-2.084-4.492-5.312-5.898-5.881c-1.836-0.678-3.086-2.103-4.647-3.528l0,0\t\t\tc0,0-0.021,0-0.021-0.06l-0.02-0.06c-0.098-0.119-0.215-0.199-0.312-0.269c-0.117-0.09-0.233-0.209-0.352-0.339\t\t\tc-1.914-1.595-9.375-8.542-9.375-8.542l-1.523,0.588l-2.266-1.515c0,0-3.613,3.797-4.004,4.375\t\t\tc-0.381,0.568-1.738,1.595-2.471,2.551c-0.205,0.25-0.557,0.697-0.986,1.186l0,0c-1.123,1.306-2.852,3.109-4.385,3.738\t\t\tc-2.109,0.837-5.732,3.309-5.732,3.309s-0.625-0.589-1.328-1.246l0,0c-0.215-0.21-0.449-0.488-0.684-0.679l0,0\t\t\tc-0.078-0.08-0.156-0.158-0.205-0.209c-0.029,0-0.029-0.062-0.049-0.062c-0.098-0.062-0.137-0.14-0.215-0.196\t\t\tc-0.029,0-0.029-0.041-0.049-0.041c-0.06-0.062-0.117-0.119-0.187-0.199c-0.021,0-0.021-0.062-0.039-0.062\t\t\tc-0.06-0.062-0.116-0.119-0.215-0.18l-0.021-0.062c-0.049-0.08-0.117-0.14-0.215-0.199c-0.957-1.125-3.809-2.699-4.922-3.309\t\t\tc-1.152-0.588-3.477,0.957-4.609,1.714c-1.133,0.737-2.285,1.713-3.457,2.182c-0.039,0-0.059,0.062-0.116,0.062\t\t\tc-0.029,0-0.029,0-0.05,0.039c-0.02,0-0.078,0.04-0.106,0.04c-0.021,0-0.021,0-0.039,0c-0.06,0.061-0.098,0.061-0.116,0.079h-0.05\t\t\tc-1.337,0.567-3.604,1.715-4.109,2.552c-0.625,0.977-2.48,2.452-4.386,3.408c-1.122,0.609-3.584,1.654-5.614,2.672\t\t\tc-1.017-0.997-1.953-1.924-2.812-2.701c-0.02-0.039-0.059-0.039-0.078-0.061c-0.127-0.1-0.215-0.208-0.293-0.27\t\t\tc-0.039-0.039-0.059-0.061-0.117-0.119c-0.059-0.08-0.176-0.158-0.215-0.199c-0.049-0.059-0.078-0.079-0.117-0.159\t\t\tc-0.098-0.06-0.137-0.119-0.215-0.14c-0.039-0.039-0.078-0.08-0.117-0.119c-0.029-0.062-0.098-0.141-0.156-0.16\t\t\tc-0.039-0.039-0.088-0.059-0.155-0.118c-0.039-0.041-0.106-0.08-0.156-0.142c-0.039-0.039-0.099-0.078-0.116-0.078\t\t\tc-0.06-0.039-0.117-0.062-0.156-0.141c-0.039-0.039-0.078-0.039-0.107-0.061c-0.049-0.062-0.088-0.062-0.127-0.08\t\t\tc-0.02,0-0.039-0.04-0.059-0.04c-0.068-0.062-0.117-0.08-0.195-0.08c-1.348-0.485-2.832-1.834-2.832-1.834s-4.59,4.865-5.195,5.022\t\t\tc-0.059,0-0.117,0.062-0.176,0.062h-0.039c-0.039,0.04-0.078,0.04-0.137,0.08l0,0l0,0c-0.605,0.271-1.387,0.797-1.387,0.797\t\t\ts-5.195-6.815-7.295-7.573c-1.847-0.697-3.097-2.104-4.64-3.539l0,0c0,0-0.021,0-0.021-0.04l-0.02-0.06\t\t\tc-0.117-0.12-0.215-0.199-0.293-0.289c0-0.114-0.098-0.203-0.234-0.323c-1.895-1.615-9.375-8.541-9.375-8.541l-1.483,0.638\t\t\tl-2.296-1.515c0,0-3.622,3.797-3.993,4.375c-0.392,0.568-1.738,1.595-2.48,2.551c-0.205,0.27-0.547,0.698-0.986,1.186l0,0\t\t\tc-1.133,1.306-2.861,3.11-4.365,3.738c-2.109,0.837-5.747,3.309-5.747,3.309s-0.62-0.568-1.318-1.246l0,0\t\t\tc-0.22-0.21-0.459-0.47-0.698-0.679l0,0c-0.073-0.08-0.142-0.159-0.21-0.209c-0.02,0-0.02-0.04-0.054-0.04\t\t\tc-0.068-0.08-0.117-0.159-0.186-0.208c-0.024,0-0.024-0.04-0.054-0.04c-0.049-0.08-0.117-0.12-0.171-0.199\t\t\tc-0.02,0-0.02-0.06-0.039-0.06c-0.049-0.061-0.117-0.12-0.171-0.18l-0.02-0.06c-0.049-0.06-0.117-0.14-0.166-0.199\t\t\tc-0.962-1.106-3.823-2.721-4.971-3.309c-1.113-0.568-3.394,0.977-4.541,1.754c-1.152,0.717-2.28,1.714-3.433,2.163\t\t\tc-0.049,0-0.068,0.06-0.117,0.06c-0.02,0-0.02,0-0.049,0.041c-0.02-0.011-0.073,0.029-0.093,0.029s-0.02,0-0.049,0\t\t\tc-0.049,0.06-0.103,0.06-0.122,0.079h0.054c-1.323,0.588-3.623,1.735-4.13,2.571c-0.581,0.957-2.471,2.432-4.39,3.408\t\t\tc-1.133,0.588-3.604,1.653-5.62,2.633c-0.962-0.959-1.943-1.924-2.812-2.692c0.083-0.021,0.054-0.021,0.029-0.06\t\t\tc-0.088-0.08-0.19-0.199-0.288-0.25c-0.039-0.039-0.068-0.061-0.122-0.119c-0.068-0.101-0.146-0.159-0.21-0.209\t\t\tc-0.049-0.049-0.068-0.061-0.117-0.119c-0.068-0.08-0.122-0.119-0.19-0.16c-0.049-0.039-0.068-0.059-0.122-0.118\t\t\tc-0.049-0.041-0.107-0.09-0.156-0.11c-0.054-0.06-0.073-0.08-0.122-0.119c-0.049-0.08-0.088-0.1-0.142-0.141\t\t\tc-0.02-0.06-0.068-0.08-0.098-0.08c-0.049-0.049-0.103-0.068-0.142-0.106c-0.02-0.062-0.068-0.062-0.098-0.08\t\t\tc-0.054-0.062-0.103-0.062-0.122-0.08c-0.02,0-0.039-0.062-0.068-0.062c-0.049-0.039-0.103-0.059-0.151-0.059\t\t\tc-1.338-0.45-2.861-1.766-2.861-1.766s-4.58,4.845-5.156,5.021c-0.044,0-0.093,0.062-0.142,0.062h-0.02\t\t\tc-0.049,0.029-0.103,0.029-0.142,0.049l0,0l0,0c-0.601,0.29-1.401,0.816-1.401,0.816s-5.107-6.776-7.197-7.494\t\t\tc-1.831-0.697-3.071-2.104-4.629-3.539l0,0c0,0-0.02,0-0.02-0.06l-0.024-0.04c-0.088-0.12-0.186-0.189-0.308-0.269\t\t\tc-0.122-0.1-0.239-0.219-0.361-0.329c-1.919-1.623-9.36-8.55-9.36-8.55l-1.539,0.569L38.111,0c0,0-3.618,3.817-4.009,4.375\t\t\tc-0.381,0.588-1.724,1.595-2.471,2.572c-0.21,0.249-0.552,0.678-0.981,1.166l0,0c-1.127,1.326-2.86,3.129-4.37,3.717\t\t\tc-2.109,0.837-5.737,3.329-5.737,3.329s-0.62-0.567-1.323-1.246l0,0c-0.21-0.199-0.449-0.468-0.688-0.679l0,0\t\t\tc-0.068-0.078-0.151-0.158-0.22-0.217c-0.02,0-0.02-0.062-0.049-0.062c-0.073-0.062-0.122-0.13-0.19-0.17\t\t\tc-0.02,0-0.02-0.061-0.054-0.061c-0.039-0.08-0.117-0.119-0.166-0.199c-0.02,0-0.02-0.042-0.054-0.042\t\t\tc-0.049-0.079-0.117-0.119-0.166-0.199l-0.02-0.05c-0.054-0.055-0.122-0.135-0.171-0.175c-0.962-1.126-3.813-2.741-4.971-3.33\t\t\tc-1.152-0.578-3.433,0.958-4.58,1.715c-1.152,0.767-2.28,1.734-3.433,2.183c-0.049,0-0.068,0.04-0.117,0.04\t\t\tc-0.02,0-0.02,0-0.049,0.061c-0.024,0-0.073,0.061-0.103,0.061s-0.02,0-0.049,0c-0.049,0.04-0.093,0.04-0.122,0.062h-0.01\t\t\tC2.779,13.404,0.669,14.48,0,15.318V24H240z\"\/>\n\t\t<\/svg><\/div><div class=\"row unequal col-double-gutter double-top-padding double-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_parent col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h1 class=\"fontsize-212837\" ><span>Viscosa<\/span><\/h1><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column text-lead\" ><p>La sensazione unica al tatto e la traspirabilit\u00e0 della viscosa a base di cellulosa la rendono ideale per gli usi di fascia alta nell'abbigliamento maschile e femminile. Grazie alla collaborazione con Enka, ci assicuriamo che sia realizzata con materiali provenienti da fonti sostenibili.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-444\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-featured.jpg\" width=\"900\" height=\"600\" alt=\"Viscosa\" title=\"\" srcset=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-featured.jpg 900w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-featured-300x200.jpg 300w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-featured-768x512.jpg 768w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-featured-18x12.jpg 18w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-featured-350x233.jpg 350w\" sizes=\"(max-width: 900px) 100vw, 900px\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><div class=\"empty-space empty-single mobile-hidden\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-color-xsdn-bg row-container\" id=\"row-unique-1\"><div class=\"row double-top-padding double-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 single-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1671538604364 border-color-gyho-color no-block-padding\" style=\"border-style: solid;border-right-width: 2px ;padding-right: 15px ;\" ><div class=\"uncont\" ><div class=\"vc_row row-internal row-container\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-450\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Taffeta.jpg\" width=\"1000\" height=\"1000\" alt=\"\" title=\"\" srcset=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Taffeta.jpg 1000w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Taffeta-300x300.jpg 300w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Taffeta-150x150.jpg 150w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Taffeta-768x768.jpg 768w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Taffeta-12x12.jpg 12w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Taffeta-350x350.jpg 350w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Taffeta-348x348.jpg 348w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-left align_left column_child col-lg-6 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h1\" ><span>Taffet\u00e0<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode-wrapper uncode-list\" >\n<ul class=\"icons\">\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>100% Taffett\u00e0 di viscosa<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Include le qualit\u00e0 V261 e V845<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>140 cm di larghezza<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Produzione europea<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Scorte nei nostri magazzini europei<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-3 half-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1671538609324 border-color-gyho-color no-block-padding\" style=\"border-style: solid;border-right-width: 2px ;padding-right: 15px ;\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h3\" ><span>Scarica la gamma Shade<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 250px;\"><a class=\"single-media-link\" href=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/ViscoseTaffeta.pdf\" target=\"_blank\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><div class=\"fluid-svg\"><span id=\"icon-149112\" style=\"width:100%\" class=\"icon-media\"><img decoding=\"async\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/fabric-sample-button-2.svg\" alt=\"\" title=\"\"><\/span><\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/a><\/div><\/div><div class=\"uncode_text_column text-small\" ><p>Questa gamma deve essere utilizzata solo a titolo indicativo, se si desidera una tonalit\u00e0 specifica. Chiedi un campione.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-2 half-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h3\" ><span>Hai una domanda?<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column\" ><p>Contattaci, saremo lieti di aiutarti.<\/p>\n<\/div><span class=\"btn-container btn-block\" ><a role=\"button\"  href=\"https:\/\/jessgrove.co.uk\/it\/contatto\/\" class=\"custom-link btn btn-sm border-width-0 btn-default btn-block btn-icon-left\" title=\"Contatto\">Contattaci<\/a><\/span><span class=\"btn-container btn-block\" ><a role=\"button\"  href=\"https:\/\/jessgrove.co.uk\/it\/contatto\/#agents\" class=\"custom-link btn btn-sm border-width-0 btn-default btn-block btn-icon-left\" title=\"Contatto\">Visualizza tutti gli agenti<\/a><\/span><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-1\" data-row=\"script-row-unique-1\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-1\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-color-lxmt-bg row-container\" id=\"row-unique-2\"><div class=\"row double-top-padding double-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 single-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1671538604364 border-color-gyho-color no-block-padding\" style=\"border-style: solid;border-right-width: 2px ;padding-right: 15px ;\" ><div class=\"uncont\" ><div class=\"vc_row row-internal row-container\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-453\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Twill.jpg\" width=\"1000\" height=\"1000\" alt=\"\" title=\"\" srcset=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Twill.jpg 1000w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Twill-300x300.jpg 300w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Twill-150x150.jpg 150w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Twill-768x768.jpg 768w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Twill-12x12.jpg 12w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Twill-350x350.jpg 350w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-Twill-348x348.jpg 348w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-left align_left column_child col-lg-6 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h1\" ><span>Twill<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode-wrapper uncode-list\" >\n<ul class=\"icons\">\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>100% Twill di viscosa<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Include le qualit\u00e0 V710, V935. Qualit\u00e0 V1125, V1744<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>140 cm di larghezza<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Produzione europea<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Scorte nei nostri magazzini europei<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-3 half-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1671538609324 border-color-gyho-color no-block-padding\" style=\"border-style: solid;border-right-width: 2px ;padding-right: 15px ;\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h3\" ><span>Scarica la gamma Shade<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 250px;\"><a class=\"single-media-link\" href=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/ViscoseTwill.pdf\" target=\"_blank\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><div class=\"fluid-svg\"><span id=\"icon-533709\" style=\"width:100%\" class=\"icon-media\"><img decoding=\"async\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/fabric-sample-button-2.svg\" alt=\"\" title=\"\"><\/span><\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/a><\/div><\/div><div class=\"uncode_text_column text-small\" ><p>Questa gamma deve essere utilizzata solo a titolo indicativo, se si desidera una tonalit\u00e0 specifica. Chiedi un campione.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-2 half-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h3\" ><span>Hai una domanda?<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column\" ><p>Contattaci, saremo lieti di aiutarti.<\/p>\n<\/div><span class=\"btn-container btn-block\" ><a role=\"button\"  href=\"https:\/\/jessgrove.co.uk\/it\/contatto\/\" class=\"custom-link btn btn-sm border-width-0 btn-default btn-block btn-icon-left\" title=\"Contatto\">Contattaci<\/a><\/span><span class=\"btn-container btn-block\" ><a role=\"button\"  href=\"https:\/\/jessgrove.co.uk\/it\/contatto\/#agents\" class=\"custom-link btn btn-sm border-width-0 btn-default btn-block btn-icon-left\" title=\"Contatto\">Visualizza tutti gli agenti<\/a><\/span><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-2\" data-row=\"script-row-unique-2\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-2\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-color-xsdn-bg row-container\" id=\"row-unique-3\"><div class=\"row double-top-padding double-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 single-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1671538604364 border-color-gyho-color no-block-padding\" style=\"border-style: solid;border-right-width: 2px ;padding-right: 15px ;\" ><div class=\"uncont\" ><div class=\"vc_row row-internal row-container\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-456\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V1001.jpg\" width=\"1000\" height=\"1000\" alt=\"\" title=\"\" srcset=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V1001.jpg 1000w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V1001-300x300.jpg 300w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V1001-150x150.jpg 150w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V1001-768x768.jpg 768w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V1001-12x12.jpg 12w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V1001-350x350.jpg 350w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V1001-348x348.jpg 348w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-left align_left column_child col-lg-6 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h1\" ><span>V1001<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode-wrapper uncode-list\" >\n<ul class=\"icons\">\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>100% Viscosa Ponge<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>140 cm di larghezza<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Morbido, leggero e utilizzato soprattutto per l'abbigliamento femminile<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Produzione europea<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Scorte nei nostri magazzini europei<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-3 half-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1671538609324 border-color-gyho-color no-block-padding\" style=\"border-style: solid;border-right-width: 2px ;padding-right: 15px ;\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h3\" ><span>Scarica la gamma Shade<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 250px;\"><a class=\"single-media-link\" href=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/V1001.pdf\" target=\"_blank\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><div class=\"fluid-svg\"><span id=\"icon-821522\" style=\"width:100%\" class=\"icon-media\"><img decoding=\"async\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/fabric-sample-button-2.svg\" alt=\"\" title=\"\"><\/span><\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/a><\/div><\/div><div class=\"uncode_text_column text-small\" ><p>Questa gamma deve essere utilizzata solo a titolo indicativo, se si desidera una tonalit\u00e0 specifica. Chiedi un campione.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-2 half-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h3\" ><span>Hai una domanda?<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column\" ><p>Contattaci, saremo lieti di aiutarti.<\/p>\n<\/div><span class=\"btn-container btn-block\" ><a role=\"button\"  href=\"https:\/\/jessgrove.co.uk\/it\/contatto\/\" class=\"custom-link btn btn-sm border-width-0 btn-default btn-block btn-icon-left\" title=\"Contatto\">Contattaci<\/a><\/span><span class=\"btn-container btn-block\" ><a role=\"button\"  href=\"https:\/\/jessgrove.co.uk\/it\/contatto\/#agents\" class=\"custom-link btn btn-sm border-width-0 btn-default btn-block btn-icon-left\" title=\"Contatto\">Visualizza tutti gli agenti<\/a><\/span><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-3\" data-row=\"script-row-unique-3\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-3\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-color-lxmt-bg row-container\" id=\"row-unique-4\"><div class=\"row double-top-padding double-bottom-padding single-h-padding limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-7 single-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1671538604364 border-color-gyho-color no-block-padding\" style=\"border-style: solid;border-right-width: 2px ;padding-right: 15px ;\" ><div class=\"uncont\" ><div class=\"vc_row row-internal row-container\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-middle pos-center align_left column_child col-lg-6 single-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 100%;\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><img decoding=\"async\" class=\"wp-image-459\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V2120.jpg\" width=\"1000\" height=\"1000\" alt=\"\" title=\"\" srcset=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V2120.jpg 1000w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V2120-300x300.jpg 300w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V2120-150x150.jpg 150w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V2120-768x768.jpg 768w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V2120-12x12.jpg 12w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V2120-350x350.jpg 350w, https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-V2120-348x348.jpg 348w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-left align_left column_child col-lg-6 half-internal-gutter\"><div class=\"uncol style-light\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h1\" ><span>Voile V2120<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode-wrapper uncode-list\" >\n<ul class=\"icons\">\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>100% Viscosa Voile<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>138 cm di larghezza<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Produzione europea<\/li>\n<li><i class=\"fa fa-check-square-o text-accent-color\"><\/i>Scorte nei nostri magazzini europei<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-3 half-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell  vc_custom_1671538609324 border-color-gyho-color no-block-padding\" style=\"border-style: solid;border-right-width: 2px ;padding-right: 15px ;\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h3\" ><span>Scarica la gamma Shade<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode-single-media  text-left\"><div class=\"single-wrapper\" style=\"max-width: 250px;\"><a class=\"single-media-link\" href=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/V2120.pdf\" target=\"_blank\"><div class=\"tmb tmb-light  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg\"><div class=\"t-inside\"><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"uncode-single-media-wrapper\"><div class=\"fluid-svg\"><span id=\"icon-584786\" style=\"width:100%\" class=\"icon-media\"><img decoding=\"async\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/fabric-sample-button-2.svg\" alt=\"\" title=\"\"><\/span><\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/a><\/div><\/div><div class=\"uncode_text_column text-small\" ><p>Questa gamma deve essere utilizzata solo a titolo indicativo, se si desidera una tonalit\u00e0 specifica. Chiedi un campione.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-2 half-internal-gutter\"><div class=\"uncol style-light unexpand\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"empty-space empty-half\" ><span class=\"empty-space-inner\"><\/span><\/div>\n<div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"h3\" ><span>Hai una domanda?<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column\" ><p>Contattaci, saremo lieti di aiutarti.<\/p>\n<\/div><span class=\"btn-container btn-block\" ><a role=\"button\"  href=\"https:\/\/jessgrove.co.uk\/it\/contatto\/\" class=\"custom-link btn btn-sm border-width-0 btn-default btn-block btn-icon-left\" title=\"Contatto\">Contattaci<\/a><\/span><span class=\"btn-container btn-block\" ><a role=\"button\"  href=\"https:\/\/jessgrove.co.uk\/it\/contatto\/#agents\" class=\"custom-link btn btn-sm border-width-0 btn-default btn-block btn-icon-left\" title=\"Contatto\">Visualizza tutti gli agenti<\/a><\/span><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-4\" data-row=\"script-row-unique-4\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-4\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row has-bg need-focus style-accent-bg row-container\" id=\"row-unique-6\"><div class=\"row col-half-gutter double-top-padding double-bottom-padding no-h-padding full-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 double-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_row row-internal row-container\"><div class=\"row row-child\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_center column_child col-lg-12 single-internal-gutter\"><div class=\"uncol style-spec style-dark\" ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap\"><div class=\"heading-text el-text\" ><h2 class=\"fontsize-212837\" ><span>Esplora la nostra gamma di prodotti<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"owl-carousel-wrapper carousel-overflow-visible\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"owl-carousel-container owl-carousel-loading double-gutter\" >\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"index-783450830\" class=\"owl-carousel owl-element owl-height-auto owl-dots-db-space owl-dots-outside owl-dots-single-block-padding owl-dots-align-center\" data-loop=\"true\" data-dots=\"true\" data-dotsmobile=\"true\" data-navmobile=\"false\" data-navspeed=\"400\" data-autoplay=\"true\" data-timeout=\"3000\" data-stagepadding=\"65\" data-lg=\"1\" data-md=\"1\" data-sm=\"1\" data-vp-height=\"false\">\t\t\t<div class=\"tmb tmb-carousel atc-typography-inherit tmb-iso-h33 tmb-round tmb-light tmb-text-showed tmb-overlay-anim tmb-content-left tmb-image-anim tmb-shadowed tmb-shadowed-darker-lg  grid-cat-4 tmb-id-478 tmb-img-ratio tmb-content-under tmb-media-first\" ><div class=\"t-inside style-color-xsdn-bg no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 50%;\"><\/div><a role=\"button\" tabindex=\"-1\" href=\"https:\/\/jessgrove.co.uk\/it\/acetate\/\" class=\"pushed\" target=\"_self\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-color-wayh-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-479\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Acetate-featured-uai-900x450.jpg\" width=\"900\" height=\"450\" alt=\"\" title=\"\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"t-entry-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"t-entry-text-tc double-block-padding\"><div class=\"t-entry\"><p class=\"t-entry-meta\"><span class=\"t-entry-category t-entry-category-4 t-entry-tax\"><a class=\"style-accent-bg tmb-term-evidence font-ui\" href=\"https:\/\/jessgrove.co.uk\/it\/category\/product\/\">Prodotto<\/a><\/span><\/p><h3 class=\"t-entry-title h3 title-scale\"><a href=\"https:\/\/jessgrove.co.uk\/it\/acetate\/\" target=\"_self\">Acetato<\/a><\/h3><div class=\"t-entry-excerpt\"><p>La naturale lucentezza dell'acetato lo rende particolarmente adatto alla moda femminile. \u00c8 anche molto comodo da indossare e offre un alto livello di \"traspirabilit\u00e0\".<\/p>\n<\/div><div class=\"spacer spacer-one single-space\"><\/div><div class=\"spacer spacer-two single-space\"><\/div><p class=\"t-entry-readmore btn-container\"><a href=\"https:\/\/jessgrove.co.uk\/it\/acetate\/\" class=\"btn btn-link\" target=\"_self\">Leggi di pi\u00f9<\/a><\/p><\/div><\/div>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-carousel atc-typography-inherit tmb-iso-h33 tmb-round tmb-light tmb-text-showed tmb-overlay-anim tmb-content-left tmb-image-anim tmb-shadowed tmb-shadowed-darker-lg  grid-cat-4 tmb-id-463 tmb-img-ratio tmb-content-under tmb-media-first\" ><div class=\"t-inside style-color-xsdn-bg no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 50%;\"><\/div><a role=\"button\" tabindex=\"-1\" href=\"https:\/\/jessgrove.co.uk\/it\/knitted\/\" class=\"pushed\" aria-label=\"Lavorata a maglia\"  target=\"_self\" data-lb-index=\"1\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-color-wayh-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-464\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Knitted-featured-uai-900x450.jpg\" width=\"900\" height=\"450\" alt=\"Lavorata a maglia\" title=\"\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"t-entry-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"t-entry-text-tc double-block-padding\"><div class=\"t-entry\"><p class=\"t-entry-meta\"><span class=\"t-entry-category t-entry-category-4 t-entry-tax\"><a class=\"style-accent-bg tmb-term-evidence font-ui\" href=\"https:\/\/jessgrove.co.uk\/it\/category\/product\/\">Prodotto<\/a><\/span><\/p><h3 class=\"t-entry-title h3 title-scale\"><a href=\"https:\/\/jessgrove.co.uk\/it\/knitted\/\" target=\"_self\">Lavorata a maglia<\/a><\/h3><div class=\"t-entry-excerpt\"><p>Le nostre maglie circolari sono morbide al tatto, estensibili e con un ottimo drappeggio. I diversi materiali hanno propriet\u00e0 diverse, tra cui l'asciugatura rapida e la capacit\u00e0 di trattenere il calore.<\/p>\n<\/div><div class=\"spacer spacer-one single-space\"><\/div><div class=\"spacer spacer-two single-space\"><\/div><p class=\"t-entry-readmore btn-container\"><a href=\"https:\/\/jessgrove.co.uk\/it\/knitted\/\" class=\"btn btn-link\" target=\"_self\">Leggi di pi\u00f9<\/a><\/p><\/div><\/div>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-carousel atc-typography-inherit tmb-iso-h33 tmb-round tmb-light tmb-text-showed tmb-overlay-anim tmb-content-left tmb-image-anim tmb-shadowed tmb-shadowed-darker-lg  grid-cat-4 tmb-id-443 tmb-img-ratio tmb-content-under tmb-media-first\" ><div class=\"t-inside style-color-xsdn-bg no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 50%;\"><\/div><a role=\"button\" tabindex=\"-1\" href=\"https:\/\/jessgrove.co.uk\/it\/viscose\/\" class=\"pushed\" aria-label=\"Viscosa\"  target=\"_self\" data-lb-index=\"2\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-color-wayh-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-444\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Viscose-featured-uai-900x450.jpg\" width=\"900\" height=\"450\" alt=\"Viscosa\" title=\"\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"t-entry-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"t-entry-text-tc double-block-padding\"><div class=\"t-entry\"><p class=\"t-entry-meta\"><span class=\"t-entry-category t-entry-category-4 t-entry-tax\"><a class=\"style-accent-bg tmb-term-evidence font-ui\" href=\"https:\/\/jessgrove.co.uk\/it\/category\/product\/\">Prodotto<\/a><\/span><\/p><h3 class=\"t-entry-title h3 title-scale\"><a href=\"https:\/\/jessgrove.co.uk\/it\/viscose\/\" target=\"_self\">Viscosa<\/a><\/h3><div class=\"t-entry-excerpt\"><p>La sensazione unica al tatto e la traspirabilit\u00e0 della viscosa a base di cellulosa la rendono ideale per gli usi di fascia alta nell'abbigliamento maschile e femminile. Grazie alla collaborazione con Enka, ci assicuriamo che sia realizzata con materiali provenienti da fonti sostenibili.<\/p>\n<\/div><div class=\"spacer spacer-one single-space\"><\/div><div class=\"spacer spacer-two single-space\"><\/div><p class=\"t-entry-readmore btn-container\"><a href=\"https:\/\/jessgrove.co.uk\/it\/viscose\/\" class=\"btn btn-link\" target=\"_self\">Leggi di pi\u00f9<\/a><\/p><\/div><\/div>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-carousel atc-typography-inherit tmb-iso-h33 tmb-round tmb-light tmb-text-showed tmb-overlay-anim tmb-content-left tmb-image-anim tmb-shadowed tmb-shadowed-darker-lg  grid-cat-4 tmb-id-428 tmb-img-ratio tmb-content-under tmb-media-first\" ><div class=\"t-inside style-color-xsdn-bg no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 50%;\"><\/div><a role=\"button\" tabindex=\"-1\" href=\"https:\/\/jessgrove.co.uk\/it\/recycled-and-sustainable\/\" class=\"pushed\" aria-label=\"Riciclato\"  target=\"_self\" data-lb-index=\"3\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-color-wayh-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-430\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Recycled-featured-uai-900x450.jpg\" width=\"900\" height=\"450\" alt=\"Riciclato\" title=\"\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"t-entry-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"t-entry-text-tc double-block-padding\"><div class=\"t-entry\"><p class=\"t-entry-meta\"><span class=\"t-entry-category t-entry-category-4 t-entry-tax\"><a class=\"style-accent-bg tmb-term-evidence font-ui\" href=\"https:\/\/jessgrove.co.uk\/it\/category\/product\/\">Prodotto<\/a><\/span><\/p><h3 class=\"t-entry-title h3 title-scale\"><a href=\"https:\/\/jessgrove.co.uk\/it\/recycled-and-sustainable\/\" target=\"_self\">Riciclato e sostenibile<\/a><\/h3><div class=\"t-entry-excerpt\"><p>Collaboriamo con i principali produttori di materiali riciclati Unifi e abbiamo una buona selezione di tessuti in poliestere realizzati, tra gli altri materiali, con bottiglie di plastica riciclate.<\/p>\n<\/div><div class=\"spacer spacer-one single-space\"><\/div><div class=\"spacer spacer-two single-space\"><\/div><p class=\"t-entry-readmore btn-container\"><a href=\"https:\/\/jessgrove.co.uk\/it\/recycled-and-sustainable\/\" class=\"btn btn-link\" target=\"_self\">Leggi di pi\u00f9<\/a><\/p><\/div><\/div>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-carousel atc-typography-inherit tmb-iso-h33 tmb-round tmb-light tmb-text-showed tmb-overlay-anim tmb-content-left tmb-image-anim tmb-shadowed tmb-shadowed-darker-lg  grid-cat-4 tmb-id-383 tmb-img-ratio tmb-content-under tmb-media-first\" ><div class=\"t-inside style-color-xsdn-bg no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 50%;\"><\/div><a role=\"button\" tabindex=\"-1\" href=\"https:\/\/jessgrove.co.uk\/it\/printed\/\" class=\"pushed\" aria-label=\"Stampato\"  target=\"_self\" data-lb-index=\"4\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-color-wayh-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-384\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Printed-featured-uai-900x450.jpg\" width=\"900\" height=\"450\" alt=\"Stampato\" title=\"\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"t-entry-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"t-entry-text-tc double-block-padding\"><div class=\"t-entry\"><p class=\"t-entry-meta\"><span class=\"t-entry-category t-entry-category-4 t-entry-tax\"><a class=\"style-accent-bg tmb-term-evidence font-ui\" href=\"https:\/\/jessgrove.co.uk\/it\/category\/product\/\">Prodotto<\/a><\/span><\/p><h3 class=\"t-entry-title h3 title-scale\"><a href=\"https:\/\/jessgrove.co.uk\/it\/printed\/\" target=\"_self\">Stampato<\/a><\/h3><div class=\"t-entry-excerpt\"><p>Per i clienti che desiderano un design personalizzato, \u00e8 possibile effettuare stampe transfer, serigrafiche e digitali su qualsiasi materiale di base; inoltre, abbiamo a disposizione una vasta gamma di design prestampati.<\/p>\n<\/div><div class=\"spacer spacer-one single-space\"><\/div><div class=\"spacer spacer-two single-space\"><\/div><p class=\"t-entry-readmore btn-container\"><a href=\"https:\/\/jessgrove.co.uk\/it\/printed\/\" class=\"btn btn-link\" target=\"_self\">Leggi di pi\u00f9<\/a><\/p><\/div><\/div>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-carousel atc-typography-inherit tmb-iso-h33 tmb-round tmb-light tmb-text-showed tmb-overlay-anim tmb-content-left tmb-image-anim tmb-shadowed tmb-shadowed-darker-lg  grid-cat-4 tmb-id-363 tmb-img-ratio tmb-content-under tmb-media-first\" ><div class=\"t-inside style-color-xsdn-bg no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 50%;\"><\/div><a role=\"button\" tabindex=\"-1\" href=\"https:\/\/jessgrove.co.uk\/it\/viscose-acetate-blends\/\" class=\"pushed\" target=\"_self\" data-lb-index=\"5\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-color-wayh-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-364\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Mixture-featured-uai-900x450.jpg\" width=\"900\" height=\"450\" alt=\"\" title=\"\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"t-entry-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"t-entry-text-tc double-block-padding\"><div class=\"t-entry\"><p class=\"t-entry-meta\"><span class=\"t-entry-category t-entry-category-4 t-entry-tax\"><a class=\"style-accent-bg tmb-term-evidence font-ui\" href=\"https:\/\/jessgrove.co.uk\/it\/category\/product\/\">Prodotto<\/a><\/span><\/p><h3 class=\"t-entry-title h3 title-scale\"><a href=\"https:\/\/jessgrove.co.uk\/it\/viscose-acetate-blends\/\" target=\"_self\">Miscele di viscosa e acetato<\/a><\/h3><div class=\"t-entry-excerpt\"><p>La combinazione di viscosa e acetato crea un attraente effetto bicolore \"cangiante\" che siamo lieti di poter offrire in un'ampia gamma di colori e design.<\/p>\n<\/div><div class=\"spacer spacer-one single-space\"><\/div><div class=\"spacer spacer-two single-space\"><\/div><p class=\"t-entry-readmore btn-container\"><a href=\"https:\/\/jessgrove.co.uk\/it\/viscose-acetate-blends\/\" class=\"btn btn-link\" target=\"_self\">Leggi di pi\u00f9<\/a><\/p><\/div><\/div>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-carousel atc-typography-inherit tmb-iso-h33 tmb-round tmb-light tmb-text-showed tmb-overlay-anim tmb-content-left tmb-image-anim tmb-shadowed tmb-shadowed-darker-lg  grid-cat-4 tmb-id-293 tmb-img-ratio tmb-content-under tmb-media-first\" ><div class=\"t-inside style-color-xsdn-bg no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 50%;\"><\/div><a role=\"button\" tabindex=\"-1\" href=\"https:\/\/jessgrove.co.uk\/it\/polyester\/\" class=\"pushed\" aria-label=\"Poliestere\"  target=\"_self\" data-lb-index=\"6\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-color-wayh-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-295\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Polyester-featured-uai-900x450.jpg\" width=\"900\" height=\"450\" alt=\"Poliestere\" title=\"\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"t-entry-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"t-entry-text-tc double-block-padding\"><div class=\"t-entry\"><p class=\"t-entry-meta\"><span class=\"t-entry-category t-entry-category-4 t-entry-tax\"><a class=\"style-accent-bg tmb-term-evidence font-ui\" href=\"https:\/\/jessgrove.co.uk\/it\/category\/product\/\">Prodotto<\/a><\/span><\/p><h3 class=\"t-entry-title h3 title-scale\"><a href=\"https:\/\/jessgrove.co.uk\/it\/polyester\/\" target=\"_self\">Poliestere<\/a><\/h3><div class=\"t-entry-excerpt\"><p>Una scelta molto popolare per molti dei nostri clienti, la nostra gamma di tessuti in poliestere offre un reale rapporto qualit\u00e0-prezzo. I tessuti sono disponibili in tinta unita, con finiture di lusso e persino in maglia.<\/p>\n<\/div><div class=\"spacer spacer-one single-space\"><\/div><div class=\"spacer spacer-two single-space\"><\/div><p class=\"t-entry-readmore btn-container\"><a href=\"https:\/\/jessgrove.co.uk\/it\/polyester\/\" class=\"btn btn-link\" target=\"_self\">Leggi di pi\u00f9<\/a><\/p><\/div><\/div>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-carousel atc-typography-inherit tmb-iso-h33 tmb-round tmb-light tmb-text-showed tmb-overlay-anim tmb-content-left tmb-image-anim tmb-shadowed tmb-shadowed-darker-lg  grid-cat-4 tmb-id-200 tmb-img-ratio tmb-content-under tmb-media-first\" ><div class=\"t-inside style-color-xsdn-bg no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 50%;\"><\/div><a role=\"button\" tabindex=\"-1\" href=\"https:\/\/jessgrove.co.uk\/it\/cotton\/\" class=\"pushed\" aria-label=\"Cotone\"  target=\"_self\" data-lb-index=\"7\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-color-wayh-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-208\" src=\"https:\/\/jessgrove.co.uk\/wp-content\/uploads\/2022\/12\/Cotton-featured-uai-900x450.jpg\" width=\"900\" height=\"450\" alt=\"Cotone\" title=\"\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"t-entry-text\">\n\t\t\t\t\t\t\t\t\t<div class=\"t-entry-text-tc double-block-padding\"><div class=\"t-entry\"><p class=\"t-entry-meta\"><span class=\"t-entry-category t-entry-category-4 t-entry-tax\"><a class=\"style-accent-bg tmb-term-evidence font-ui\" href=\"https:\/\/jessgrove.co.uk\/it\/category\/product\/\">Prodotto<\/a><\/span><\/p><h3 class=\"t-entry-title h3 title-scale\"><a href=\"https:\/\/jessgrove.co.uk\/it\/cotton\/\" target=\"_self\">Cotone \/ misto cotone<\/a><\/h3><div class=\"t-entry-excerpt\"><p>Traspiranti, lavabili e morbidi al tatto, i nostri capi in cotone 100% e in misto cotone 65% e poliestere 35% sono perfetti sia stampati che in tinta unita.<\/p>\n<\/div><div class=\"spacer spacer-one single-space\"><\/div><div class=\"spacer spacer-two single-space\"><\/div><p class=\"t-entry-readmore btn-container\"><a href=\"https:\/\/jessgrove.co.uk\/it\/cotton\/\" class=\"btn btn-link\" target=\"_self\">Leggi di pi\u00f9<\/a><\/p><\/div><\/div>\n\t\t\t\t\t\t\t<\/div><\/div><\/div>\t\t<\/div>\t\n\t\n\n\t<\/div>\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-6\" data-row=\"script-row-unique-6\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-6\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La sensazione unica al tatto e la traspirabilit\u00e0 della viscosa a base di cellulosa la rendono ideale per gli usi di fascia alta nell'abbigliamento maschile e femminile. Grazie alla collaborazione con Enka, ci assicuriamo che sia realizzata con materiali provenienti da fonti sostenibili.<\/p>","protected":false},"author":4,"featured_media":444,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product"],"_links":{"self":[{"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/posts\/443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/comments?post=443"}],"version-history":[{"count":0,"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/posts\/443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/media\/444"}],"wp:attachment":[{"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/media?parent=443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/categories?post=443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jessgrove.co.uk\/it\/wp-json\/wp\/v2\/tags?post=443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}